{"id":2052,"date":"2019-05-25T09:46:22","date_gmt":"2019-05-25T07:46:22","guid":{"rendered":"http:\/\/www.carmelocelona.com\/?p=2052"},"modified":"2022-02-11T09:50:54","modified_gmt":"2022-02-11T08:50:54","slug":"blu-e-il-mito-della-caverna-il-dipinto-murale-della-ex-casa-del-portuale-a-messina","status":"publish","type":"post","link":"https:\/\/www.carmelocelona.com\/index.php\/2019\/05\/25\/blu-e-il-mito-della-caverna-il-dipinto-murale-della-ex-casa-del-portuale-a-messina\/","title":{"rendered":"\u201cBlu\u201d e il mito della caverna:  Il dipinto murale della ex Casa del Portuale a Messina"},"content":{"rendered":"<p>Secondo Platone alcuni uomini sono prigionieri di una visione deformata e imposta della realt\u00e0, prigionieri e incatenati, fin dalla nascita, dentro una caverna, costretti a guardare solo la parete di fondo ove scambiano le ombre su essa proiettate con la realt\u00e0. In questa metafora chi riesce a vedere la realt\u00e0 \u00e8 solo colui che sta fuori dalla caverna o colui che riesce a spezzare le catene ed uscire fuori.<\/p>\n<p>Cos\u00ec accade che un artista esogeno soggiorna solo qualche giorno in una citt\u00e0 sconosciuta ove abitano uomini costretti in una caverna mentale e riesce a rappresentarla nel modo pi\u00f9 chiaro ed icastico che nessun artista o intellettuale autoctono sia mai riuscito a descrivere meglio. \u00a0Ed ecco che d\u2019improvviso un mattino del 2013, nella zona pi\u00f9 degradata del centro di Messina, paradossalmente anche la pi\u00f9 significativa (l\u2019ansa di un porto naturale per secoli sede del Palazzo Reale che dopo il terremoto del 1908 venne relegata, pi\u00f9 prosaicamente, ad attivit\u00e0 portuale: granai, magazzini generali, mercato ittico, dogana, casa del portuale, ecc\u2026 Edifici oggi colpiti da un\u2019esorabile obsolescenza e che versano afflitti nell\u2019abbandono e nel degrado), appare sul muro sberciato dell\u2019<em>ex Casa del Portuale <\/em>di via Alessio Valore, uno straordinario murales che mozza il fiato per la sua lucidit\u00e0 iconologica. Un\u2019 illustrazione oggettiva e incontestabile della realt\u00e0. Messa l\u00ec a brutto muso. Un\u2019opera presto riconosciuta come un capolavoro della <em>Street Art.<\/em><\/p>\n<p><em><u>La Street Art<\/u><\/em><\/p>\n<p>L\u2019arte di strada o arte urbana \u00e8 una forma d\u2019arte contemporanea che si manifesta in luoghi pubblici. Nasce e viene praticata come espressione artistica di contestazione e di critica al dilagante degrado delle citt\u00e0 e delle metropoli. Un fenomeno artistico che pi\u00f9 di altri si attesta il ruolo, doveroso dell\u2019arte, della denunzia. Una corrente espressiva che a dirla con Camus \u201c<strong><em>ci d\u00e0 l\u2019ultima prospettiva della rivolta<\/em><\/strong>\u201d. Un\u2019 esperienza espressiva che denuncia la perdita della qualit\u00e0 urbana come lucida metafora del decadimento morale e civile dell\u2019attuale contesto storico. Contrasta il degrado urbano e quello delle \u201cperiferie dei perdenti\u201d con nuove forme d\u2019arte di grande valore artistico e d\u2019impegno civile ed etico, trasformando i \u201cnon luoghi\u201d delle citt\u00e0 postmoderne in luoghi urbani dove esporre nuove forme d\u2019arte. Si tratta di autentiche opere d\u2019arte fruibili da tutti. Con la <em>Street Art <\/em>\u00e8 l\u2019arte che arriva a tutti, soprattutto agli ultimi, ai diseredati, di cui spesso denuncia la condizione. Un\u2019arte dal grande impatto visivo che si mette a disposizione del popolo per stimolare sentimenti di rivolta e indignazione. Nasce, intorno al 2000, dall\u2019esigenza di esprimere quella tensione sociale e di massa che in quegli anni si identificava nelle lotte contro la globalizzazione. Il fenomeno a 20 anni dalle sue prime espressioni ha assunto un grande valore artistico e culturale diffondendosi su tutto il pianeta. Con la <em>Street Art<\/em> gli artisti tornano ad essere militanti, come i muralisti messicani degli anni venti del secolo scorso. Oggi gli epigoni dei grandi Diego Rivera, Jos\u00e8 Clemente Orozco, David Alfaro Siqueiros, sono l\u2019americano Haring,\u00a0 l\u2019inglese Banksy, il Francese J.R. e l\u2019italiano Blu.<\/p>\n<p><em><u>Blu<\/u><\/em><\/p>\n<p><strong><em>\u201cBlu\u201d<\/em><\/strong>, considerato dalla critica uno dei primi <em>street artist<\/em> al mondo, \u00e8 un artista fantasma quasi leggendario. Di lui si sa molto poco, mantiene l\u2019anonimato, non si espone ai media, non rilascia interviste, non fa dichiarazioni.\u00a0 Le sue opere, diffuse in tutto il pianeta, affrontano i temi della denuncia sociale e dell\u2019impegno civile. Sempre a sostegno delle lotte contro il potere economico e politico. Accorre ovunque per sostenere con i suoi dipinti, di grande visibilit\u00e0, le lotte ambientaliste, anti militariste, anti globalizzazione. Con la notevole bellezza delle sue opere si batte contro tutte le ingiustizie e gli orrori del capitalismo. Con il suo pennello esprime eclatanti ed efficaci accuse ad ogni forma di violenza militare o civile perpetrata sui popoli pi\u00f9 poveri e sui soggetti pi\u00f9 deboli. Lancia messaggi di pacifismo e le sue iconografie fustigano i potenti ed istigano al riscatto sociale, raccontano l\u2019allarmante insulto delle multinazionali all\u2019ambiente e alle strutture democratiche. La caratteristica ricorrente dei suoi interventi \u00e8 l\u2019invasione inaspettata di luoghi e ambiti urbani degradati nei quali realizza opere finalizzate a stimolare processi di consapevolezza che inducano alla riqualificazione urbana, ambientale e civile. Con il suo stile limpido e diretto, il suo messaggio immediato, per quanto surreale, le sue opere hanno sempre un grande impatto sociale e comunicano in modo vivo ed efficace i loro contenuti. La singolarit\u00e0 della sua cifra stilistica lo connota e lo fa risultare riconoscibile al punto che la sua espressivit\u00e0 semiotica \u00e8 divenuta il significante della lotta per i diritti umani e dei valori universali della democrazia e della pace. Ha realizzato opere notevoli in tutte le parti del mondo: in Sud America (Argentina, Brasile, Uruguay, Bolivia, Per\u00f9, Bolivia);in Centro America ( Nicaragua , Costarica, Guatemala, Messico);in Nord America (New York, long Island, Los Angeles);in Medio Oriente (Palestina, Siria, Libano);In Europa (Germania, Polonia, Rep. Ceca, Francia, Spagna, Portogallo, Inghilterra, Norvegia, Serbia, Grecia). Le sue opere sono molto diffuse anche in Italia: Bologna, Milano, Torino, Firenze, Roma, Modena, Ancona, Jesi, Senigallia, Prato, Grosseto, Rovigo, Verona, Pesaro, Campobasso, Taranto, Niscemi, Sassari e Messina;<\/p>\n<p><em><u>Il dipinto della Casa del Portuale a Messina<\/u><\/em><\/p>\n<p>Il dipinto sul prospetto dell\u2019ex Casa del Portuale realizzato da \u201c<em>Blu<\/em>\u201d sbalordisce per la capacit\u00e0 di lettura del contesto sociale messinese da parte dell\u2019autore. L\u2019opera \u00e8 una lucida ed efficace rappresentazione di tutte le patologie sociali di cui la citt\u00e0 soffre: da quelle pi\u00f9 acute e contemporanee a quelle ormai croniche frutto della secolarizzazione di quelle asimmetrie di trattamento innescate durante la ricostruzione della citt\u00e0 e del tessuto sociale dopo il terremoto del 1908. \u201c<em>Blu<\/em>\u201d in quest\u2019opera riesce a sintetizzare nella forma pi\u00f9 diretta e pi\u00f9 efficace la condizione sociale di una comunit\u00e0 ridotta ad un sempre attuale gregariato mortificante indirizzato verso taluni sistemi di potere che gestiscono con categorie feudali le sorti della citt\u00e0, determinando perpetue condizioni di bisogno che trasformano i diritti in favori e i favori in miracoli. La sua iconologia \u00e8 una lampante metafora di come alcune strutture di potere formatisi grazie a rendite di posizione, al controllo amministrativo e alla speculazione sul territorio abbiano reso subalterne le istituzioni e sottomesso ogni coscienza. \u201c<em>Blu<\/em>\u201d nel muro dell\u2019abbandonata <em>Casa del Portuale<\/em> ha rappresentato esplicitamente la rassegnazione e l\u2019assenza di diritti, la mancanza di rispetto della dignit\u00e0 umana e di servizi, la mortificante prevalenza della mediocrit\u00e0 sul merito. Il dipinto \u00e8 una lunga narrazione terrificante, nella quale non emerge solo la denunzia dello status quo, ma \u00e8 netto lo sprone, mediato dalla metafora del pescespada (archetipo dello Stretto) che infilza i falsi miti e simboli del potere, ad assumere atteggiamenti che liberino dall\u2019opprimente sistema rappresentato. Questa nitida raffigurazione della crisi culturale e sociale della comunit\u00e0 messinese e delle dinamiche sociali della citt\u00e0 esorta ad una resurrezione collettiva che liberi dalla mentalit\u00e0 del favore e del comparaggio ormai divenuta \u201cforma culturale autoctona\u201d. I contenuti iconografici e culturali, la tecnica adottata e la bellezza formale e cromatica, fanno di questo dipinto murale una vera opera d\u2019arte. Tra le poche espressioni artistiche di alto livello e di autentico senso che si possono registrare nella Messina contemporanea. Come diceva sempre Camus \u201c<em>L\u2019arte contemporanea sceglie la morale ed esilia la bellezza<\/em>\u201d<\/p>\n<p>Adesso il dipinto \u00e8 stato vandalizzato e versa in gravi condizioni. Nessuna autorit\u00e0 \u00e8 riuscita a salvaguardarlo, a tutelarlo, a vincolarlo, a riconoscere il suo valore artistico e culturale. Il \u201cprogetto di riabilitazione civile dell\u2019ex casa del portuale\u201d (primo esempio in Italia di progettazione partecipata per il riuso di un bene comune), che prevedeva anche un dispositivo di protezione dell\u2019opera, \u00e8 stato miseramente accantonato. Molto ha contribuito l\u2019esercizio inconsulto di fare <em>Street Art<\/em> negli edifici pubblici limitrofi, nel tentativo grottesco di emulare \u201cBlu\u201d. Dipinti murali, ad esso \u00a0affiancati, di cui sfugge il senso, i cui contenuti iconologici hanno stemperato in modo autoimmune i termini della denuncia dell\u2019opera dell\u2019artista fantasma, aggiungendo solo degrado al degrado. Cos\u00ec la banalit\u00e0 lo ha cancellato ancor pi\u00f9 dei vandali. La patetica e scomposta voglia di incrociare i pennelli con \u201cBlu\u201d da parte di afasici artisti totalmente disimpegnati (come macilenti mingherlini che ambiscono di incrociare i guantoni con Cassius Clay, credendo davvero di metterlo K.O.) ne ha svuotato l\u2019enorme valore semiotico. Nessuno di questi che abbia colto ed elaborato l\u2019esortante metafora del pescespada. Nessuno che abbia declinato, seppur con altra cifra, la lucida denuncia delle condizioni civili e delle dinamiche sociali rappresentate da \u201cBlu\u201d. Il dipinto di \u201cBlu\u201d ha scosso le coscienze emergendo dal degrado, i nuovi murales le sopiscono rafforzando il degrado e con la loro insensatezza lo risucchiano nell\u2019oblio a cui loro sono destinate. Forse sono espressione di una collettivit\u00e0 che non vuol vedere la sua condizione disperata di popolo vinto, forse sono il significante di un istinto comune che sceglie di restare genuflesso dentro la caverna. \u201c<strong><em>Cu camina calatu torci a schina, s&#8217;\u00e8 un populu torci a storia<\/em><\/strong>.\u201d diceva Ignazio Buttitta. Cos\u00ec quella Storia che altrove ha sconfitto il feudalesimo a Messina ha trovato un muro\u2026 Quel muro dove \u00e8 stata cancellata la verit\u00e0 dipinta da \u201cBlu\u201d.<\/p>\n<p>Carmelo Celona<\/p>\n<p>25.05.2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo Platone alcuni uomini sono prigionieri di una visione deformata e imposta della realt\u00e0, prigionieri e incatenati, fin dalla nascita, dentro una caverna, costretti a guardare solo la parete di<\/p>\n","protected":false},"author":1,"featured_media":2056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/posts\/2052"}],"collection":[{"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/comments?post=2052"}],"version-history":[{"count":2,"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/posts\/2052\/revisions"}],"predecessor-version":[{"id":2062,"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/posts\/2052\/revisions\/2062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/media\/2056"}],"wp:attachment":[{"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/media?parent=2052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/categories?post=2052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carmelocelona.com\/index.php\/wp-json\/wp\/v2\/tags?post=2052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}